{"id":152,"date":"2023-10-11T11:24:56","date_gmt":"2023-10-11T09:24:56","guid":{"rendered":"https:\/\/dansecouple.fr\/?page_id=152"},"modified":"2023-10-11T11:24:56","modified_gmt":"2023-10-11T09:24:56","slug":"nos-cours","status":"publish","type":"page","link":"https:\/\/dansecouple.fr\/index.php\/nos-cours\/","title":{"rendered":"Nos cours"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"class_list":["post-152","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nos cours -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dansecouple.fr\/index.php\/nos-cours\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nos cours -\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dansecouple.fr\/index.php\/nos-cours\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dansecouple.fr\\\/index.php\\\/nos-cours\\\/\",\"url\":\"https:\\\/\\\/dansecouple.fr\\\/index.php\\\/nos-cours\\\/\",\"name\":\"Nos cours -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dansecouple.fr\\\/#website\"},\"datePublished\":\"2023-10-11T09:24:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dansecouple.fr\\\/index.php\\\/nos-cours\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dansecouple.fr\\\/index.php\\\/nos-cours\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dansecouple.fr\\\/index.php\\\/nos-cours\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dansecouple.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nos cours\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dansecouple.fr\\\/#website\",\"url\":\"https:\\\/\\\/dansecouple.fr\\\/\",\"name\":\"\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dansecouple.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nos cours -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dansecouple.fr\/index.php\/nos-cours\/","og_locale":"fr_FR","og_type":"article","og_title":"Nos cours -","og_url":"https:\/\/dansecouple.fr\/index.php\/nos-cours\/","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dansecouple.fr\/index.php\/nos-cours\/","url":"https:\/\/dansecouple.fr\/index.php\/nos-cours\/","name":"Nos cours -","isPartOf":{"@id":"https:\/\/dansecouple.fr\/#website"},"datePublished":"2023-10-11T09:24:56+00:00","breadcrumb":{"@id":"https:\/\/dansecouple.fr\/index.php\/nos-cours\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dansecouple.fr\/index.php\/nos-cours\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dansecouple.fr\/index.php\/nos-cours\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dansecouple.fr\/"},{"@type":"ListItem","position":2,"name":"Nos cours"}]},{"@type":"WebSite","@id":"https:\/\/dansecouple.fr\/#website","url":"https:\/\/dansecouple.fr\/","name":"","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dansecouple.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/dansecouple.fr\/index.php\/wp-json\/wp\/v2\/pages\/152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dansecouple.fr\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dansecouple.fr\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dansecouple.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dansecouple.fr\/index.php\/wp-json\/wp\/v2\/comments?post=152"}],"version-history":[{"count":1,"href":"https:\/\/dansecouple.fr\/index.php\/wp-json\/wp\/v2\/pages\/152\/revisions"}],"predecessor-version":[{"id":153,"href":"https:\/\/dansecouple.fr\/index.php\/wp-json\/wp\/v2\/pages\/152\/revisions\/153"}],"wp:attachment":[{"href":"https:\/\/dansecouple.fr\/index.php\/wp-json\/wp\/v2\/media?parent=152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}